{"id":2109,"count":1,"description":"","link":"https:\/\/boardgamewire.com\/index.php\/tag\/fulfilllment\/","name":"fulfilllment","slug":"fulfilllment","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/boardgamewire.com\/index.php\/tag\/fulfilllment\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2109\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boardgamewire.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/boardgamewire.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/index.php\\\/tag\\\/fulfilllment\\\/#listItem\",\"name\":\"fulfilllment\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/index.php\\\/tag\\\/fulfilllment\\\/#listItem\",\"position\":2,\"name\":\"fulfilllment\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boardgamewire.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2109\\\/#collectionpage\",\"url\":\"https:\\\/\\\/boardgamewire.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2109\\\/\",\"name\":\"fulfilllment -\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2109\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/#organization\",\"name\":\"BoardGameWire\",\"description\":\"The world's leading source of news and analysis for board game industry professionals\",\"url\":\"https:\\\/\\\/boardgamewire.com\\\/\",\"email\":\"mike@boardgamewire.com\",\"foundingDate\":\"2023-04-24\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/boardgamewire.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-BoardGameWire-The-world-s-leading-source-of-industry-news-and-analysis-for-board-game-professionals-1.png\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2109\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2109\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/boardgamewire\",\"https:\\\/\\\/twitter.com\\\/board_game_wire\",\"https:\\\/\\\/bsky.app\\\/profile\\\/boardgamewire.bsky.social\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/#website\",\"url\":\"https:\\\/\\\/boardgamewire.com\\\/\",\"name\":\"BoardGameWire\",\"alternateName\":\"boardgamewire.com\",\"description\":\"The world's leading source of news and analysis for board game industry professionals\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/boardgamewire.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"fulfilllment -","description":"","canonical_url":"https:\/\/boardgamewire.com\/index.php\/tag\/fulfilllment\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/boardgamewire.com\/wp-json\/wp\/v2\/tags\/2109\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/boardgamewire.com#listItem","position":1,"name":"Home","item":"https:\/\/boardgamewire.com","nextItem":{"@type":"ListItem","@id":"https:\/\/boardgamewire.com\/index.php\/tag\/fulfilllment\/#listItem","name":"fulfilllment"}},{"@type":"ListItem","@id":"https:\/\/boardgamewire.com\/index.php\/tag\/fulfilllment\/#listItem","position":2,"name":"fulfilllment","previousItem":{"@type":"ListItem","@id":"https:\/\/boardgamewire.com#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/boardgamewire.com\/wp-json\/wp\/v2\/tags\/2109\/#collectionpage","url":"https:\/\/boardgamewire.com\/wp-json\/wp\/v2\/tags\/2109\/","name":"fulfilllment -","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/boardgamewire.com\/#website"},"breadcrumb":{"@id":"https:\/\/boardgamewire.com\/wp-json\/wp\/v2\/tags\/2109\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/boardgamewire.com\/#organization","name":"BoardGameWire","description":"The world's leading source of news and analysis for board game industry professionals","url":"https:\/\/boardgamewire.com\/","email":"mike@boardgamewire.com","foundingDate":"2023-04-24","logo":{"@type":"ImageObject","url":"https:\/\/boardgamewire.com\/wp-content\/uploads\/2023\/04\/cropped-BoardGameWire-The-world-s-leading-source-of-industry-news-and-analysis-for-board-game-professionals-1.png","@id":"https:\/\/boardgamewire.com\/wp-json\/wp\/v2\/tags\/2109\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/boardgamewire.com\/wp-json\/wp\/v2\/tags\/2109\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/boardgamewire","https:\/\/twitter.com\/board_game_wire","https:\/\/bsky.app\/profile\/boardgamewire.bsky.social"]},{"@type":"WebSite","@id":"https:\/\/boardgamewire.com\/#website","url":"https:\/\/boardgamewire.com\/","name":"BoardGameWire","alternateName":"boardgamewire.com","description":"The world's leading source of news and analysis for board game industry professionals","inLanguage":"en-GB","publisher":{"@id":"https:\/\/boardgamewire.com\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/boardgamewire.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tfulfilllment\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/boardgamewire.com"},{"label":"fulfilllment","link":"https:\/\/boardgamewire.com\/index.php\/tag\/fulfilllment\/"}],"_links":{"self":[{"href":"https:\/\/boardgamewire.com\/index.php\/wp-json\/wp\/v2\/tags\/2109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boardgamewire.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/boardgamewire.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/boardgamewire.com\/index.php\/wp-json\/wp\/v2\/posts?tags=2109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}